{"id":3375,"date":"2021-10-26T15:12:47","date_gmt":"2021-10-26T08:12:47","guid":{"rendered":"http:\/\/sala108.com\/online\/?post_type=product&#038;p=3375"},"modified":"2021-11-05T11:33:17","modified_gmt":"2021-11-05T04:33:17","slug":"%e0%b8%89%e0%b8%b2%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a7%e0%b8%b2%e0%b8%94%e0%b8%94%e0%b8%ad%e0%b8%81%e0%b9%84%e0%b8%a1","status":"publish","type":"product","link":"https:\/\/sala108.com\/shop\/product\/%e0%b8%89%e0%b8%b2%e0%b8%81%e0%b8%81%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a7%e0%b8%b2%e0%b8%94%e0%b8%94%e0%b8%ad%e0%b8%81%e0%b9%84%e0%b8%a1\/","title":{"rendered":"\u0e09\u0e32\u0e01\u0e01\u0e31\u0e49\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e20\u0e32\u0e1e\u0e27\u0e32\u0e14\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3376 size-full\" src=\"http:\/\/sala108.com\/shop\/\/wp-content\/uploads\/2021\/10\/1737_P_1482313807325.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807325.jpg 600w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807325-350x467.jpg 350w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807325-338x450.jpg 338w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807325-450x600.jpg 450w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807325-113x150.jpg 113w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807325-263x350.jpg 263w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3377 size-full\" src=\"http:\/\/sala108.com\/shop\/\/wp-content\/uploads\/2021\/10\/1737_P_1482313807530.jpg\" alt=\"\" width=\"600\" height=\"1067\" srcset=\"https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807530.jpg 600w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807530-350x622.jpg 350w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807530-253x450.jpg 253w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807530-337x600.jpg 337w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807530-84x150.jpg 84w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807530-197x350.jpg 197w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3378 size-full\" src=\"http:\/\/sala108.com\/shop\/\/wp-content\/uploads\/2021\/10\/1737_P_1482313807763.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807763.jpg 600w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807763-350x467.jpg 350w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807763-338x450.jpg 338w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807763-450x600.jpg 450w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807763-113x150.jpg 113w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807763-263x350.jpg 263w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3379 size-full\" src=\"http:\/\/sala108.com\/shop\/\/wp-content\/uploads\/2021\/10\/1737_P_1482313807868.jpg\" alt=\"\" width=\"600\" height=\"1067\" srcset=\"https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807868.jpg 600w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807868-350x622.jpg 350w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807868-253x450.jpg 253w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807868-337x600.jpg 337w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807868-84x150.jpg 84w, https:\/\/sala108.com\/shop\/wp-content\/uploads\/2021\/10\/1737_P_1482313807868-197x350.jpg 197w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><br \/>\n<script><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e09\u0e32\u0e01\u0e01\u0e31\u0e49\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e1e\u0e27\u0e32\u0e14<br \/>\n\u0e0a\u0e38\u0e14 4 \u0e1a\u0e32\u0e19 \u0e02\u0e19\u0e32\u0e14\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1a\u0e32\u0e19 40&#215;150 \u0e0b\u0e21.<br \/>\n\u0e27\u0e32\u0e14\u0e20\u0e32\u0e1e 2 \u0e14\u0e49\u0e32\u0e19 \u0e23\u0e32\u0e04\u0e32\u0e0a\u0e38\u0e14\u0e25\u0e30 5300 \u0e1a\u0e32\u0e17<br \/>\n\u0e27\u0e32\u0e14\u0e20\u0e32\u0e1e 1 \u0e14\u0e49\u0e32\u0e19 \u0e23\u0e32\u0e04\u0e32\u0e0a\u0e38\u0e14\u0e25\u0e30 4800 \u0e1a\u0e32\u0e17<\/p>\n<p>\u0e20\u0e32\u0e1e\u0e27\u0e32\u0e14\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e20\u0e32\u0e1e\u0e27\u0e32\u0e14\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e20\u0e32\u0e1e\u0e01\u0e25\u0e49\u0e27\u0e22\u0e44\u0e21\u0e49 \u0e20\u0e32\u0e1e\u0e14\u0e2d\u0e01\u0e25\u0e35\u0e25\u0e32\u0e27\u0e14\u0e35 \u0e20\u0e32\u0e1e\u0e27\u0e34\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<br \/>\n\u0e2a\u0e31\u0e48\u0e07\u0e17\u0e33\u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a \u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e17\u0e33 5-7 \u0e27\u0e31\u0e19<\/p>\n<p>\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<br \/>\n\u0e2a\u0e31\u0e48\u0e49\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e48\u0e07\u0e17\u0e33\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<br \/>\n\u0e42\u0e17\u0e23\/\u0e44\u0e25\u0e19\u0e4c 0811120563<\/p>\n","protected":false},"featured_media":3376,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[35,15],"product_tag":[],"class_list":{"0":"post-3375","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-35","7":"product_cat-15","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/sala108.com\/shop\/wp-json\/wp\/v2\/product\/3375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sala108.com\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sala108.com\/shop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sala108.com\/shop\/wp-json\/wp\/v2\/comments?post=3375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sala108.com\/shop\/wp-json\/wp\/v2\/media\/3376"}],"wp:attachment":[{"href":"https:\/\/sala108.com\/shop\/wp-json\/wp\/v2\/media?parent=3375"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sala108.com\/shop\/wp-json\/wp\/v2\/product_brand?post=3375"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sala108.com\/shop\/wp-json\/wp\/v2\/product_cat?post=3375"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sala108.com\/shop\/wp-json\/wp\/v2\/product_tag?post=3375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}